{"id":7009,"date":"2026-02-17T14:28:48","date_gmt":"2026-02-17T13:28:48","guid":{"rendered":"https:\/\/settanta7.com\/progetti\/cittadella-museo\/"},"modified":"2026-05-04T11:32:42","modified_gmt":"2026-05-04T10:32:42","slug":"cittadella-museo","status":"publish","type":"progetti","link":"https:\/\/settanta7.com\/en\/projects\/cittadella-museo\/","title":{"rendered":"Museum Citadel"},"featured_media":7010,"template":"","meta":{"galleria_immagini":[],"galleria_immagini_riga_1":["https:\/\/settanta7.com\/wp-content\/uploads\/2026\/02\/Settanta7_Projects_Podgorica_01-01.jpg","https:\/\/settanta7.com\/wp-content\/uploads\/2026\/02\/Settanta7_Projects_Podgorica_02-02.jpg"],"galleria_immagini_riga_2":["https:\/\/settanta7.com\/wp-content\/uploads\/2026\/02\/Settanta7_Projects_Podgorica_02-03.jpg","https:\/\/settanta7.com\/wp-content\/uploads\/2026\/02\/Settanta7_Projects_Podgorica_02-01.jpg","https:\/\/settanta7.com\/wp-content\/uploads\/2026\/02\/Settanta7_Projects_Podgorica_01-02.jpg"],"galleria_immagini_riga_3":[],"galleria_immagini_riga_4":[],"galleria_immagini_riga_5":[],"galleria_immagini_riga_6":[],"galleria_immagini_riga_7":[]},"tipologia":[70,92],"class_list":["post-7009","progetti","type-progetti","status-publish","has-post-thumbnail","hentry","tipologia-cultura","tipologia-culture"],"_links":{"self":[{"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/progetti\/7009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/progetti"}],"about":[{"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/types\/progetti"}],"version-history":[{"count":1,"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/progetti\/7009\/revisions"}],"predecessor-version":[{"id":7016,"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/progetti\/7009\/revisions\/7016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/media\/7010"}],"wp:attachment":[{"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/media?parent=7009"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/settanta7.com\/en\/wp-json\/wp\/v2\/tipologia?post=7009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}